{"id":5308,"date":"2024-05-31T08:58:59","date_gmt":"2024-05-31T06:58:59","guid":{"rendered":"http:\/\/92.60.32.103\/~rcrindus\/secteurs-industriels\/aeronautics-and-space-industry\/"},"modified":"2026-03-31T13:16:19","modified_gmt":"2026-03-31T11:16:19","slug":"plancher-pour-laeronautique-et-lespace","status":"publish","type":"page","link":"https:\/\/www.rcrindustrialflooring.com\/fr\/secteurs-industriels\/plancher-pour-laeronautique-et-lespace\/","title":{"rendered":"Plancher pour\u00a0l&#8217;a\u00e9ronautique et l&#8217;espace"},"content":{"rendered":"<section class=\"bde-section-5308-173 bde-section\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"section-container\"><div class=\"bde-columns-5308-174 bde-columns\"><div class=\"bde-column-5308-175 bde-column\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-dual-heading-5308-176 bde-dual-heading\">\n\n\n            <span data-style=\"primary\" class=\"dual-heading--primary  \">Plancher pour<\/span>\n\n            <span data-style=\"secondary\" class=\"dual-heading--secondary  js-annotate\"> l'a\u00e9ronautique et l'espace<\/span>\n\n\n\n<\/h1><div class=\"bde-rich-text-5308-177 bde-rich-text breakdance-rich-text-styles\">\n<p>Bienvenue chez RCR Industrial Flooring<strong> Leaders du monde plat<\/strong>. Nous sommes sp\u00e9cialis\u00e9s dans la conception et la r\u00e9alisation de <strong>sols industriels en b\u00e9ton<\/strong>.<\/p>\n<\/div>\n<\/div><\/div><div class=\"bde-div-5308-199 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-button-5308-200 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"#footer\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Contact<\/span>\n\n                            \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-5308-109 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-5308-110 bde-columns\"><div class=\"bde-column-5308-111 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-5308-112 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-5308-113 bde-text\">\nLES EXIGENCES DU MONDE L'A\u00c9RONAUTIQUE ET L'ESPACE\n<\/div>\n<\/div><h2 class=\"bde-heading-5308-114 bde-heading\">\nLeaders dans les services de rev\u00eatement de sol pour les industries a\u00e9ronautiques et spatiales\n<\/h2><div class=\"bde-rich-text-5308-115 bde-rich-text breakdance-rich-text-styles\">\n<p>Les rev\u00eatements de sol pour les industries a\u00e9ronautique et spatiale sont essentiels, car ces environnements exigent les normes les plus \u00e9lev\u00e9es en mati\u00e8re de pr\u00e9cision, de durabilit\u00e9 et de s\u00e9curit\u00e9. Nos solutions de rev\u00eatement de sol sp\u00e9cialis\u00e9es sont con\u00e7ues pour r\u00e9pondre aux exigences rigoureuses des installations a\u00e9rospatiales, offrant des performances et une fiabilit\u00e9 in\u00e9gal\u00e9es.<\/p>\n<p>Nos planchers sont con\u00e7us pour r\u00e9sister \u00e0 des conditions extr\u00eames, notamment \u00e0 de grandes variations de temp\u00e9rature, \u00e0 de lourdes charges et \u00e0 l'exposition \u00e0 des produits chimiques et \u00e0 des carburants. Ils offrent une r\u00e9sistance et une durabilit\u00e9 exceptionnelles, garantissant qu'ils peuvent supporter le poids des composants des avions et des engins spatiaux sans compromettre l'int\u00e9grit\u00e9 structurelle.<\/p>\n<p>En outre, nos syst\u00e8mes de rev\u00eatement de sol sont con\u00e7us pour une propret\u00e9 et un entretien optimaux. Les surfaces sans joints r\u00e9duisent le risque de contamination et facilitent le nettoyage, ce qui est essentiel pour maintenir l'environnement st\u00e9rile requis pour les applications a\u00e9rospatiales. Les propri\u00e9t\u00e9s antistatiques garantissent en outre la s\u00e9curit\u00e9 des \u00e9quipements \u00e9lectroniques sensibles utilis\u00e9s dans l'industrie.<\/p>\n<p>Gr\u00e2ce \u00e0 des mat\u00e9riaux avanc\u00e9s qui garantissent une stabilit\u00e9 et des performances \u00e0 long terme, nos solutions de rev\u00eatement de sol offrent \u00e9galement une isolation thermique qui permet de g\u00e9rer efficacement les niveaux de temp\u00e9rature. Disponibles dans diverses options personnalisables, ces sols allient fonctionnalit\u00e9 et esth\u00e9tique, et s'int\u00e8grent parfaitement \u00e0 la nature high-tech et pr\u00e9cise des environnements de l'industrie a\u00e9rospatiale et spatiale.<\/p>\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-5308-121 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-5308-122 bde-heading\">\nCaract\u00e9ristiques essentielles pour les industries a\u00e9ronautiques et spatiales\n<\/h2><div class=\"bde-rich-text-5308-123 bde-rich-text breakdance-rich-text-styles\">\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-fwpde-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-fwpde-1n7m0yu\">\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-216\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"18f2de49-b318-445d-86f5-10896582f255\">\n<div class=\"result-streaming markdown prose w-full break-words dark:prose-invert dark\">\n<p>Les caract\u00e9ristiques de nos sols pour l'industrie a\u00e9ronautique et spatiale sont sp\u00e9cialement con\u00e7ues pour r\u00e9pondre aux exigences rigoureuses de ces environnements de haute technologie. Ces sols offrent une durabilit\u00e9 et une r\u00e9sistance exceptionnelles pour supporter le poids \u00e9lev\u00e9 des composants des avions et des engins spatiaux. Ils sont con\u00e7us pour r\u00e9sister aux variations de temp\u00e9rature extr\u00eames et aux conditions difficiles, ce qui garantit des performances fiables dans toutes les situations.<\/p>\n<p>Les syst\u00e8mes de rev\u00eatement de sol offrent une excellente isolation et gestion thermiques, essentielles pour maintenir des temp\u00e9ratures stables dans les installations a\u00e9rospatiales. Ils pr\u00e9sentent \u00e9galement des propri\u00e9t\u00e9s antistatiques qui prot\u00e8gent les \u00e9quipements \u00e9lectroniques sensibles des d\u00e9charges \u00e9lectrostatiques.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"bde-columns-5308-124 bde-columns\"><div class=\"bde-column-5308-125 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-5308-201 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M501.1 395.7L384 278.6c-23.1-23.1-57.6-27.6-85.4-13.9L192 158.1V96L64 0 0 64l96 128h62.1l106.6 106.6c-13.6 27.8-9.2 62.3 13.9 85.4l117.1 117.1c14.6 14.6 38.2 14.6 52.7 0l52.7-52.7c14.5-14.6 14.5-38.2 0-52.7zM331.7 225c28.3 0 54.9 11 74.9 31l19.4 19.4c15.8-6.9 30.8-16.5 43.8-29.5 37.1-37.1 49.7-89.3 37.9-136.7-2.2-9-13.5-12.1-20.1-5.5l-74.4 74.4-67.9-11.3L334 98.9l74.4-74.4c6.6-6.6 3.4-17.9-5.7-20.2-47.4-11.7-99.6.9-136.6 37.9-28.5 28.5-41.9 66.1-41.2 103.6l82.1 82.1c8.1-1.9 16.5-2.9 24.7-2.9zm-103.9 82l-56.7-56.7L18.7 402.8c-25 25-25 65.5 0 90.5s65.5 25 90.5 0l123.6-123.6c-7.6-19.9-9.9-41.6-5-62.7zM64 472c-13.2 0-24-10.8-24-24 0-13.3 10.7-24 24-24s24 10.7 24 24c0 13.2-10.7 24-24 24z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h3 class=\"ee-iconbox-title bde-h3\" >Faible entretien<\/h3>\n        <div class=\"ee-iconbox-text\" >Con\u00e7us pour faciliter l'entretien, ils r\u00e9duisent les temps d'arr\u00eat et les co\u00fbts.<\/div>\n    <\/div>\n\n<\/div>\n<\/div><div class=\"bde-column-5308-127 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-5308-202 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M288 256c53 0 96-42.1 96-94 0-40-57.1-120.7-83.2-155.6-6.4-8.5-19.2-8.5-25.6 0C249.1 41.3 192 122 192 162c0 51.9 43 94 96 94zm277.3 72.1c-11.8-10.7-30.2-10-42.6 0L430.3 402c-11.3 9.1-25.4 14-40 14H272c-8.8 0-16-7.2-16-16s7.2-16 16-16h78.3c15.9 0 30.7-10.9 33.3-26.6 3.3-20-12.1-37.4-31.6-37.4H192c-27 0-53.1 9.3-74.1 26.3L71.4 384H16c-8.8 0-16 7.2-16 16v96c0 8.8 7.2 16 16 16h356.8c14.5 0 28.6-4.9 40-14L564 377c15.2-12.1 16.4-35.3 1.3-48.9z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h3 class=\"ee-iconbox-title bde-h3\" >Facile \u00e0 nettoyer<\/h3>\n        <div class=\"ee-iconbox-text\" >Simplifie l'entretien et l'hygi\u00e8ne, ce qui est crucial pour l'efficacit\u00e9 op\u00e9rationnelle. <\/div>\n    <\/div>\n\n<\/div>\n<\/div><div class=\"bde-column-5308-129 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-5308-203 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon-codepen\" viewBox=\"0 0 32 32\">\n<path d=\"M29.555 11.501l-14-9.333c-0.336-0.224-0.774-0.224-1.109 0l-14 9.333c-0.278 0.185-0.445 0.498-0.445 0.832v9.333c0 0.334 0.167 0.647 0.445 0.832l14 9.333c0.168 0.112 0.361 0.168 0.555 0.168s0.387-0.056 0.555-0.168l14-9.333c0.278-0.185 0.445-0.498 0.445-0.832v-9.333c0-0.334-0.167-0.647-0.445-0.832zM15 20.465l-5.197-3.465 5.197-3.465 5.197 3.465-5.197 3.465zM16 11.798v-6.93l11.197 7.465-5.197 3.465-6-4zM14 11.798l-6 4-5.197-3.465 11.197-7.465v6.93zM6.197 17l-4.197 2.798v-5.596l4.197 2.798zM8 18.202l6 4v6.93l-11.197-7.465 5.197-3.465zM16 22.202l6-4 5.197 3.465-11.197 7.465v-6.93zM23.803 17l4.197-2.798v5.596l-4.197-2.798z\"\/>\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h3 class=\"ee-iconbox-title bde-h3\" >Sans joints<\/h3>\n        <div class=\"ee-iconbox-text\" >Permet d'obtenir une surface uniforme sans joints, ce qui facilite les op\u00e9rations.<\/div>\n    <\/div>\n\n<\/div>\n<\/div><div class=\"bde-column-5308-131 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-5308-204 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 496 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M248 8C111.03 8 0 119.03 0 256s111.03 248 248 248 248-111.03 248-248S384.97 8 248 8zm0 488.21C115.34 496.21 7.79 388.66 7.79 256S115.34 15.79 248 15.79 488.21 123.34 488.21 256 380.66 496.21 248 496.21zm0-459.92C126.66 36.29 28.29 134.66 28.29 256S126.66 475.71 248 475.71 467.71 377.34 467.71 256 369.34 36.29 248 36.29zm0 431.22c-116.81 0-211.51-94.69-211.51-211.51S131.19 44.49 248 44.49 459.51 139.19 459.51 256 364.81 467.51 248 467.51zm186.23-162.98a191.613 191.613 0 0 1-20.13 48.69l-74.13-35.88 61.48 54.82a193.515 193.515 0 0 1-37.2 37.29l-54.8-61.57 35.88 74.27a190.944 190.944 0 0 1-48.63 20.23l-27.29-78.47 4.79 82.93c-8.61 1.18-17.4 1.8-26.33 1.8s-17.72-.62-26.33-1.8l4.76-82.46-27.15 78.03a191.365 191.365 0 0 1-48.65-20.2l35.93-74.34-54.87 61.64a193.85 193.85 0 0 1-37.22-37.28l61.59-54.9-74.26 35.93a191.638 191.638 0 0 1-20.14-48.69l77.84-27.11-82.23 4.76c-1.16-8.57-1.78-17.32-1.78-26.21 0-9 .63-17.84 1.82-26.51l82.38 4.77-77.94-27.16a191.726 191.726 0 0 1 20.23-48.67l74.22 35.92-61.52-54.86a193.85 193.85 0 0 1 37.28-37.22l54.76 61.53-35.83-74.17a191.49 191.49 0 0 1 48.65-20.13l26.87 77.25-4.71-81.61c8.61-1.18 17.39-1.8 26.32-1.8s17.71.62 26.32 1.8l-4.74 82.16 27.05-77.76c17.27 4.5 33.6 11.35 48.63 20.17l-35.82 74.12 54.72-61.47a193.13 193.13 0 0 1 37.24 37.23l-61.45 54.77 74.12-35.86a191.515 191.515 0 0 1 20.2 48.65l-77.81 27.1 82.24-4.75c1.19 8.66 1.82 17.5 1.82 26.49 0 8.88-.61 17.63-1.78 26.19l-82.12-4.75 77.72 27.09z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h3 class=\"ee-iconbox-title bde-h3\" >A l'\u00e9preuve de la poussi\u00e8re<\/h3>\n        <div class=\"ee-iconbox-text\" >Minimise l'accumulation de poussi\u00e8re, gardant l'espace de travail propre et s\u00fbr.<\/div>\n    <\/div>\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-5308-133 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-5308-134 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-5308-135 bde-text\">\nD\u00c9VELOPPER UNE TECHNOLOGIE UNIQUE POUR CHAQUE TYPE DE SOL\n<\/div>\n<\/div><h2 class=\"bde-heading-5308-136 bde-heading\">\nRCR Systems pour l'industrie a\u00e9ronautique et spatiale\n<\/h2><div class=\"bde-rich-text-5308-137 bde-rich-text breakdance-rich-text-styles\">\n<p style=\"text-align: center;\">Nous avons d\u00e9velopp\u00e9 des syst\u00e8mes exclusifs pour chaque type de surface qui garantissent toutes les fonctionnalit\u00e9s n\u00e9cessaires du sol pour se conformer aux r\u00e9glementations en vigueur dans chaque secteur.<\/p>\n<\/div><\/div>\n<\/section><section class=\"bde-section-5308-150 bde-section\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"section-container\"><div class=\"bde-div-5308-151 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-5308-152 bde-text\">\nNOS PROJETS\n<\/div>\n<\/div><h2 class=\"bde-heading-5308-153 bde-heading\">\nIndustries a\u00e9ronautiques et spatialesProjets de rev\u00eatement de sol\n<\/h2><div class=\"bde-text-5308-154 bde-text\">\nNotre vaste portefeuille de rev\u00eatements de sol pour l'industrie a\u00e9ronautique et spatiale t\u00e9moigne de notre profonde compr\u00e9hension et de notre capacit\u00e9 \u00e0 r\u00e9pondre aux exigences sp\u00e9cifiques de ces secteurs. Qu'il s'agisse de vastes installations de fabrication a\u00e9rospatiale ou de laboratoires spatiaux de haute pr\u00e9cision, nous fournissons des rev\u00eatements de sol qui garantissent la s\u00e9curit\u00e9 et l'efficacit\u00e9 des op\u00e9rations, ainsi que la conformit\u00e9 aux normes rigoureuses de l'industrie. Chaque installation est m\u00e9ticuleusement planifi\u00e9e et ex\u00e9cut\u00e9e pour maximiser les performances du sol et soutenir les op\u00e9rations critiques de ces environnements \u00e0 enjeux \u00e9lev\u00e9s.\n<\/div><div class=\"bde-div-5308-155 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-button-5308-156 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--custom bde-button__button\" href=\"#footer\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Contact<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-div-5308-157 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-star-rating-5308-158 bde-star-rating\">\n\n\n<div class='bde-star-rating__label' >\n  + 3.000 clients internationaux satisfaits<\/div>\n\n  <div class='bde-star-rating__wrapper'>\n    <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\"  role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-star fa-w-18 fa-2x\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\" class=\"\"><\/path><\/svg>\n    <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\"  role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-star fa-w-18 fa-2x\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\" class=\"\"><\/path><\/svg>\n    <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\"  role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-star fa-w-18 fa-2x\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\" class=\"\"><\/path><\/svg>\n    <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\"  role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-star fa-w-18 fa-2x\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\" class=\"\"><\/path><\/svg>\n    <svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\"  role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" class=\"svg-inline--fa fa-star fa-w-18 fa-2x\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\" class=\"\"><\/path><\/svg>\n  <\/div>\n\n\n\n<svg width=\"0\" height=\"0\">\n<linearGradient id=\"starhalf158\" x1=\"0\" x2=\"100%\" y1=\"0\" y2=\"0\">\n        <stop offset=\"30%\" stop-color=\"#FFF900FF\"><\/stop>\n \t\t<stop offset=\"30%\" stop-color=\"var(--bde-brand-primary-color)\"><\/stop>\n<\/linearGradient>\n<\/svg>\n\n<\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-5308-159 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-gallery-5308-160 bde-gallery\">\n\n\n  \n\n\n\n\n\n\n\n\n\n\n<div class=\"ee-gallery ee-gallery--default ee-gallery--grid ee-gallery--single ee-gallery-- ee-gallery-- ee-gallery--caption- ee-gallery--caption-none ee-gallery--ratio\">\n                  \n      <div class=\"ee-gallery-item ee-gallery-item--image ee-gallery-item--single\" href=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1.jpg\"  data-sub-html=\"<span>MODELO ALPINO<\/span>\" data-category=\"1\"                  data-lg-size=\"1920-1440\"\n\n      >\n        <figure class=\"ee-gallery-item-figure\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-1024x768.jpg\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1.jpg 1920w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-300x225.jpg 300w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-1024x768.jpg 1024w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-768x576.jpg 768w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-1536x1152.jpg 1536w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-500x375.jpg 500w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-800x600.jpg 800w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFA_Morocco_Casablanca-Airport_HQ_2017-1-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\">\n          \n                  <\/figure>\n      <\/div>\n\n                \n      <div class=\"ee-gallery-item ee-gallery-item--image ee-gallery-item--single\" href=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-scaled.jpg\"  data-sub-html=\"<span>MODELO ALPINO<\/span>\" data-category=\"1\"                  data-lg-size=\"2560-1213\"\n\n      >\n        <figure class=\"ee-gallery-item-figure\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-1024x485.jpg\" width=\"1024\" height=\"485\" srcset=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-scaled.jpg 2560w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-300x142.jpg 300w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-1024x485.jpg 1024w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-768x364.jpg 768w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-1536x728.jpg 1536w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-2048x971.jpg 2048w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-500x237.jpg 500w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-800x379.jpg 800w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-1280x607.jpg 1280w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/angar-1920x910.jpg 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\">\n          \n                  <\/figure>\n      <\/div>\n\n                \n      <div class=\"ee-gallery-item ee-gallery-item--image ee-gallery-item--single\" href=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1.jpg\"  data-sub-html=\"<span>MODELO PIRINEO<\/span>\" data-category=\"1\"                  data-lg-size=\"1280-853\"\n\n      >\n        <figure class=\"ee-gallery-item-figure\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1.jpg 1280w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-300x200.jpg 300w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-1024x682.jpg 1024w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-768x512.jpg 768w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-500x333.jpg 500w, https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/11\/RCRFP_Francia_Airbus-Nantes_LQ-1-800x533.jpg 800w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\">\n          \n                  <\/figure>\n      <\/div>\n\n      \n  <\/div>\n\n\n\n<\/div><\/div>\n<\/section><section class=\"bde-section-5308-147 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-5308-148 bde-heading\">\nNos clients internationaux pour l'industrie a\u00e9ronautique et spatiale\n<\/h2><div class=\"bde-logo-list-5308-149 bde-logo-list un-image-carousel-container\">\n\n  <div class=\"un-logo-bar__marquee-content carousel-type__stop-on-hover\">\n                            <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/Diseno_sin_titulo__4_-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/www.rcrindustrialflooring.com\/wp-content\/uploads\/2024\/07\/2-removebg-preview.png\" width=\"300\" height=\"151\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\n        <\/div>\n                      <\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-5308-161 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-dual-heading-5308-162 bde-dual-heading\">\n\n\n            <span data-style=\"secondary\" class=\"dual-heading--secondary  js-annotate\">FAQ<\/span>\n\n\n\n<\/h2><div class=\"bde-rich-text-5308-163 bde-rich-text breakdance-rich-text-styles\">\n<p>Nos FAQ se penchent sur les d\u00e9fis sp\u00e9cifiques et les solutions de rev\u00eatement de sol pour les industries a\u00e9ronautique et spatiale. D\u00e9couvrez comment nos syst\u00e8mes de rev\u00eatement de sol avanc\u00e9s r\u00e9sistent aux conditions extr\u00eames, d\u00e9couvrez nos solutions pour g\u00e9rer les variations de temp\u00e9rature et comprenez les avantages de nos rev\u00eatements de sol durables et n\u00e9cessitant peu d'entretien. Ces questions et r\u00e9ponses fournissent des informations essentielles pour prendre des d\u00e9cisions \u00e9clair\u00e9es sur le rev\u00eatement de sol de votre installation, en veillant \u00e0 ce qu'il r\u00e9ponde aux normes \u00e9lev\u00e9es requises pour la s\u00e9curit\u00e9, la performance et le progr\u00e8s technologique dans les environnements a\u00e9ronautiques et spatiaux.<\/p>\n<\/div><div class=\"bde-div-5308-164 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-frequently-asked-questions-5308-165 bde-frequently-asked-questions\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-165-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-165-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Qu'est-ce qui rend les rev\u00eatements de sol pour les industries a\u00e9ronautique et spatiale uniques ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m11 11h-7.25c-.414 0-.75.336-.75.75s.336.75.75.75h7.25v7.25c0 .414.336.75.75.75s.75-.336.75-.75v-7.25h7.25c.414 0 .75-.336.75-.75s-.336-.75-.75-.75h-7.25v-7.25c0-.414-.336-.75-.75-.75s-.75.336-.75.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m21 11.75c0-.414-.336-.75-.75-.75h-16.5c-.414 0-.75.336-.75.75s.336.75.75.75h16.5c.414 0 .75-.336.75-.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-165-button-1\" id=\"bde-faq-165-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Les sols destin\u00e9s \u00e0 l'industrie a\u00e9ronautique et spatiale sont con\u00e7us pour r\u00e9sister \u00e0 des conditions extr\u00eames, telles que les variations de temp\u00e9rature, les charges lourdes et l'exposition aux produits chimiques et aux carburants. En outre, ils poss\u00e8dent des propri\u00e9t\u00e9s antistatiques pour prot\u00e9ger les \u00e9quipements \u00e9lectroniques sensibles et des surfaces sans coutures pour faciliter le nettoyage et minimiser l'accumulation de particules.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-165-button-2\" aria-expanded=\"false\" aria-controls=\"bde-faq-165-2\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Comment les sols aident-ils \u00e0 g\u00e9rer les variations de temp\u00e9rature dans les installations a\u00e9rospatiales ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m11 11h-7.25c-.414 0-.75.336-.75.75s.336.75.75.75h7.25v7.25c0 .414.336.75.75.75s.75-.336.75-.75v-7.25h7.25c.414 0 .75-.336.75-.75s-.336-.75-.75-.75h-7.25v-7.25c0-.414-.336-.75-.75-.75s-.75.336-.75.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m21 11.75c0-.414-.336-.75-.75-.75h-16.5c-.414 0-.75.336-.75.75s.336.75.75.75h16.5c.414 0 .75-.336.75-.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-165-button-2\" id=\"bde-faq-165-2\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Nos sols pr\u00e9sentent d'excellentes propri\u00e9t\u00e9s d'isolation thermique, ce qui permet de maintenir des temp\u00e9ratures stables dans les installations a\u00e9rospatiales. Cela est essentiel pour prot\u00e9ger les composants et les \u00e9quipements sensibles qui peuvent \u00eatre affect\u00e9s par des changements de temp\u00e9rature soudains.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-165-button-3\" aria-expanded=\"false\" aria-controls=\"bde-faq-165-3\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Pourquoi la r\u00e9sistance chimique est-elle importante pour les rev\u00eatements de sol dans l'industrie spatiale ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m11 11h-7.25c-.414 0-.75.336-.75.75s.336.75.75.75h7.25v7.25c0 .414.336.75.75.75s.75-.336.75-.75v-7.25h7.25c.414 0 .75-.336.75-.75s-.336-.75-.75-.75h-7.25v-7.25c0-.414-.336-.75-.75-.75s-.75.336-.75.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m21 11.75c0-.414-.336-.75-.75-.75h-16.5c-.414 0-.75.336-.75.75s.336.75.75.75h16.5c.414 0 .75-.336.75-.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-165-button-3\" id=\"bde-faq-165-3\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>La r\u00e9sistance aux produits chimiques est essentielle pour les sols de l'industrie spatiale, car ces environnements peuvent \u00eatre expos\u00e9s \u00e0 des carburants, des lubrifiants et d'autres produits chimiques corrosifs. Nos sols sont con\u00e7us pour r\u00e9sister \u00e0 ces agents, ce qui garantit une durabilit\u00e9 et une s\u00e9curit\u00e9 \u00e0 long terme sur le lieu de travail.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-165-button-4\" aria-expanded=\"false\" aria-controls=\"bde-faq-165-4\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Quels sont les avantages des sols \u00e0 faible entretien dans les installations a\u00e9rospatiales ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m11 11h-7.25c-.414 0-.75.336-.75.75s.336.75.75.75h7.25v7.25c0 .414.336.75.75.75s.75-.336.75-.75v-7.25h7.25c.414 0 .75-.336.75-.75s-.336-.75-.75-.75h-7.25v-7.25c0-.414-.336-.75-.75-.75s-.75.336-.75.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m21 11.75c0-.414-.336-.75-.75-.75h-16.5c-.414 0-.75.336-.75.75s.336.75.75.75h16.5c.414 0 .75-.336.75-.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-165-button-4\" id=\"bde-faq-165-4\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Les sols \u00e0 faible entretien r\u00e9duisent le temps et les co\u00fbts associ\u00e9s au nettoyage et \u00e0 l'entretien r\u00e9guliers. En outre, leurs surfaces sans joints facilitent le nettoyage et contribuent \u00e0 maintenir un environnement exempt de contaminants, ce qui est crucial dans les environnements o\u00f9 la puret\u00e9 de l'air est essentielle.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-165-button-5\" aria-expanded=\"false\" aria-controls=\"bde-faq-165-5\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Comment vos sols garantissent-ils la conformit\u00e9 aux normes de l'industrie a\u00e9rospatiale ?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m11 11h-7.25c-.414 0-.75.336-.75.75s.336.75.75.75h7.25v7.25c0 .414.336.75.75.75s.75-.336.75-.75v-7.25h7.25c.414 0 .75-.336.75-.75s-.336-.75-.75-.75h-7.25v-7.25c0-.414-.336-.75-.75-.75s-.75.336-.75.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" stroke-linejoin=\"round\" stroke-miterlimit=\"2\" viewBox=\"0 0 24 24\"><path d=\"m21 11.75c0-.414-.336-.75-.75-.75h-16.5c-.414 0-.75.336-.75.75s.336.75.75.75h16.5c.414 0 .75-.336.75-.75z\" fill-rule=\"nonzero\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-165-button-5\" id=\"bde-faq-165-5\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Nos sols sont con\u00e7us et fabriqu\u00e9s pour r\u00e9pondre aux normes et r\u00e9glementations les plus strictes de l'industrie a\u00e9rospatiale. Cela inclut des tests rigoureux de r\u00e9sistance, de durabilit\u00e9 et de propri\u00e9t\u00e9s antistatiques, garantissant que nos solutions de rev\u00eatement de sol ne se contentent pas de r\u00e9pondre aux attentes en mati\u00e8re de performance et de s\u00e9curit\u00e9 requises dans ce secteur, mais qu'elles les d\u00e9passent.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Plancher pour l&#8217;a\u00e9ronautique et l&#8217;espace Bienvenue chez RCR Industrial Flooring Leaders du monde plat. Nous sommes sp\u00e9cialis\u00e9s dans la conception et la r\u00e9alisation de sols industriels en b\u00e9ton. Contact LES EXIGENCES DU MONDE L&#8217;A\u00c9RONAUTIQUE ET L&#8217;ESPACE Leaders dans les services de rev\u00eatement de sol pour les industries a\u00e9ronautiques et spatiales Les rev\u00eatements de sol pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5274,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-5308","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/pages\/5308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/comments?post=5308"}],"version-history":[{"count":8,"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/pages\/5308\/revisions"}],"predecessor-version":[{"id":24910,"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/pages\/5308\/revisions\/24910"}],"up":[{"embeddable":true,"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/pages\/5274"}],"wp:attachment":[{"href":"https:\/\/www.rcrindustrialflooring.com\/fr\/wp-json\/wp\/v2\/media?parent=5308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}